{"id":2995,"date":"2022-11-29T19:25:43","date_gmt":"2022-11-29T19:25:43","guid":{"rendered":"https:\/\/www.sidwaya.info\/sport\/?p=2995"},"modified":"2022-11-29T19:25:43","modified_gmt":"2022-11-29T19:25:43","slug":"lettre-du-sportif-12","status":"publish","type":"post","link":"https:\/\/www.sidwaya.info\/sport\/2022\/11\/29\/lettre-du-sportif-12\/","title":{"rendered":"Lettre du sportif"},"content":{"rendered":"<p>Cher Cousin,<br \/>\nJe voulais saluer l\u2019esprit de grandeur du s\u00e9lectionneur national Hubert Velud \u00e0 la suite de son \u00ab d\u00e9gage \u00bb adress\u00e9 au pr\u00e9sident de l\u2019Association des journalistes sportifs du Burkina \u00e0 Marrakech apr\u00e8s la victoire des \u00c9talons face aux El\u00e9phants. Il a rencontr\u00e9 J\u00e9r\u00f4me Tiendrebeogo pour fumer le calumet de la paix et demander pardon. Cela a \u00e9t\u00e9 accept\u00e9. L\u2019incident est ainsi clos. F\u00e9licitations aux deux pour leur maturit\u00e9 et leur grandeur d&rsquo;esprit. C&rsquo;est un bel exemple pour tous. C&rsquo;est le football burkinab\u00e8 qui gagne.<\/p>\n<p>Mais, avec le recul, j\u2019ai l\u2019impression que Velud \u00ab\u00a0guettait\u00a0\u00bb la presse. Je dis cela car la conf\u00e9rence de presse avant le d\u00e9part de l\u2019\u00e9quipe pour Marrakech a \u00e9t\u00e9 houleuse. Hubert Velud a \u00e9t\u00e9 copieusement \u00ab cuisin\u00e9 \u00bb. L\u2019on sentait vraiment la tension.<\/p>\n<p>Bref, qu\u2019il se ressaisisse et \u00e9vite d\u2019avoir un tel comportement surtout \u00e0 l\u2019encontre de la presse avec qui il est cens\u00e9 avoir une bonne et meilleure collaboration. Sinon\u2026<\/p>\n<p>Couse, la F\u00e9d\u00e9ration burkinab\u00e8 de football a encore perdu un proc\u00e8s. Apr\u00e8s celui contre l\u2019ex-entraineur des \u00c9talons locaux Seydou Zerbo dit Kroll et compagnie, c\u2019est au tour de l\u2019ex-gestionnaire des cars de la structure f\u00e9d\u00e9rale Ibrahim Kongzabr\u00e9, d\u00e9mis de ses fonctions par le maitre des lieux, d\u2019ester en justice contre la faiti\u00e8re du football national. Finalement, la justice lui a donn\u00e9 raison avec un d\u00e9dommagement \u00e0 la cl\u00e9. De toutes les fa\u00e7ons, je te ferai entendre l\u2019int\u00e9ress\u00e9.<\/p>\n<p>Avant de te dire aurevoir, je voulais te donner mon appr\u00e9ciation sur les \u00e9quipes africaines \u00e0 la pr\u00e9sente Coupe du Monde. Il est vrai que la comp\u00e9tition est en cours, mais de ce que j\u2019ai vu d\u2019elles, certaines n\u2019ont pas le niveau de cette comp\u00e9tition. Je citerai par exemple le Cameroun. Beaucoup de choses manquent \u00e0 cette \u00e9quipe. Si individuellement les Lions indomptables s\u2019en sortent, ce n\u2019est pas le cas sur le plan collectif et tactique. Sur ce dernier plan, j\u2019ai envie de douter des comp\u00e9tences de leur ma\u00eetre \u00e0 penser. En fran\u00e7ais facile, leur entraineur Rigobert Song n\u2019a pas le niveau d\u2019une telle comp\u00e9tition o\u00f9 les donn\u00e9es tactiques sont importantes pour d\u00e9cider de l\u2019issue d\u2019un match.<\/p>\n<p>Par contre, j\u2019ai \u00e9t\u00e9 s\u00e9duit par une formation comme celle des Lions de l\u2019Atlas du Maroc, tombeurs des Diables rouges de la Belgique. Cette \u00e9quipe marocaine, si elle garde la m\u00eame constance, peut pr\u00e9valoir une satisfaction au continent africain.<\/p>\n<p>Porte-toi bien.<\/p>\n<p>Par ton Cousin.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cher Cousin, Je voulais saluer l\u2019esprit de grandeur du s\u00e9lectionneur national Hubert Velud \u00e0 la suite de son \u00ab d\u00e9gage \u00bb adress\u00e9 au pr\u00e9sident de l\u2019Association des journalistes sportifs du Burkina \u00e0 Marrakech apr\u00e8s la victoire des \u00c9talons face aux El\u00e9phants. Il a rencontr\u00e9 J\u00e9r\u00f4me Tiendrebeogo pour fumer le calumet de la paix et demander [&hellip;]<\/p>\n","protected":false},"author":136,"featured_media":2313,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[33,19,39,37],"tags":[55,774,553,746],"class_list":{"0":"post-2995","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-actualites","8":"category-football","9":"category-la-une-site","10":"category-sport","11":"tag-fbf","12":"tag-hubert-velud","13":"tag-lettre-du-sportif","14":"tag-mondial-qatar-2022"},"jetpack_featured_media_url":"https:\/\/www.sidwaya.info\/sport\/wp-content\/uploads\/sites\/6\/2022\/06\/La-lettre-du-sportif-scaled-e1655056585200.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pamO1T-Mj","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/posts\/2995","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/users\/136"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/comments?post=2995"}],"version-history":[{"count":0,"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/posts\/2995\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/media\/2313"}],"wp:attachment":[{"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/media?parent=2995"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/categories?post=2995"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/tags?post=2995"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}