{"id":4179,"date":"2023-11-22T21:26:00","date_gmt":"2023-11-22T21:26:00","guid":{"rendered":"https:\/\/www.sidwaya.info\/sport\/?p=4179"},"modified":"2023-11-22T21:26:00","modified_gmt":"2023-11-22T21:26:00","slug":"crise-du-football-burkinabe-la-fbf-sexcuse-les-clubs-recusent","status":"publish","type":"post","link":"https:\/\/www.sidwaya.info\/sport\/2023\/11\/22\/crise-du-football-burkinabe-la-fbf-sexcuse-les-clubs-recusent\/","title":{"rendered":"Crise du football burkinab\u00e8: la FBF s\u2019excuse, les clubs r\u00e9cusent"},"content":{"rendered":"<p><strong>L\u2019affaire sur les retenues de 25% sur les subventions des clubs revers\u00e9es auTr\u00e9sor public a pris une autre tournure ces derniers jours. D\u00e9sormais, une trentaine de clubs demandent le d\u00e9part du pr\u00e9sident de la F\u00e9d\u00e9ration burkinab\u00e8 de football, Lazare Banss\u00e9. Ce qui a pouss\u00e9 le pr\u00e9sident du Comit\u00e9 national olympique et des sports burkinab\u00e8, Singapinda Jean Yam\u00e9ogo, \u00e0 reprendre sa casquette de m\u00e9diateur. <\/strong><\/p>\n<p>Assembl\u00e9e g\u00e9n\u00e9rale de la F\u00e9d\u00e9ration burkinab\u00e8 de football (FBF), le 18 ao\u00fbt 2023 \u00e0 Ouagadougou. Des clubs r\u00e9clament la restitution des 25\u2105 de la bourse destin\u00e9e \u00e0 l&rsquo;organisation des championnats jeunes. L\u2019ann\u00e9e tire vers sa fin. Les clubs ne voient rien venir. Comme un mot d\u2019ordre, ils envoient simultan\u00e9ment, certains \u00e0 travers leur Ligue, des correspondances de menaces \u00e0 la faiti\u00e8re du football.<\/p>\n<p>Avec des ultimatums, ils informent la FBF de la suspension de leur participation aux diff\u00e9rentes comp\u00e9titions organis\u00e9es par la FBF jusqu\u2019\u00e0 nouvel ordre. Leur menace est mise \u00e0 ex\u00e9cution \u00e0 travers des conf\u00e9rences de presse \u00e0 Bobo-Dioulasso et \u00e0 Ouagadougou. Les journ\u00e9es 10 et 11 du championnat D1 sont boycott\u00e9es. Pas de championnat non plus pour la 2e division. Du c\u00f4t\u00e9 du Fonds national pour la promotion du sport et des loisirs (FNPSL), l\u2019on est sto\u00efque. Il r\u00e9clame les justificatifs de la 1re et 2e tranche de la subvention.<\/p>\n<p>N\u2019en disposant pas puisque le championnat de petites cat\u00e9gories n\u2019a pas pu \u00eatre organis\u00e9, la FBF d\u00e9cide autrement. Comme un signe de frustration, elle libelle un ch\u00e8que de 84 millions de FCFA au FNPSL repr\u00e9sentant la retenue des 25% des tranches 1 et 2 de la subvention de la saison 2022-2023. 72 heures apr\u00e8s, 11 clubs de D1 et 17 de D2 piquent une col\u00e8re noire. Ils d\u00e9cident de passer \u00e0 l\u2019offensive. Un autre rendez-vous pour le 28 novembre prochain A travers une p\u00e9tition, ils demandent la d\u00e9mission du pr\u00e9sident de la FBF, Lazare Banss\u00e9.<\/p>\n<figure id=\"attachment_4181\" aria-describedby=\"caption-attachment-4181\" style=\"width: 620px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4181\" data-permalink=\"https:\/\/www.sidwaya.info\/sport\/2023\/11\/22\/crise-du-football-burkinabe-la-fbf-sexcuse-les-clubs-recusent\/lazare\/\" data-orig-file=\"https:\/\/www.sidwaya.info\/sport\/wp-content\/uploads\/sites\/6\/2023\/11\/lazare.gif\" data-orig-size=\"620,361\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"lazare\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Jean Yam\u00e9ogo et son staff pr\u00f4nent la s\u00e9r\u00e9nit\u00e9, \u00e0 quelques semaines&lt;br \/&gt;\nde la CAN. &lt;\/p&gt;\n\" data-medium-file=\"https:\/\/www.sidwaya.info\/sport\/wp-content\/uploads\/sites\/6\/2023\/11\/lazare-300x175.gif\" data-large-file=\"https:\/\/www.sidwaya.info\/sport\/wp-content\/uploads\/sites\/6\/2023\/11\/lazare.gif\" class=\"size-full wp-image-4181\" src=\"https:\/\/www.sidwaya.info\/sport\/wp-content\/uploads\/sites\/6\/2023\/11\/lazare.gif\" alt=\"\" width=\"620\" height=\"361\" \/><figcaption id=\"caption-attachment-4181\" class=\"wp-caption-text\">Jean Yam\u00e9ogo et son staff pr\u00f4nent la s\u00e9r\u00e9nit\u00e9, \u00e0 quelques semaines<br \/>de la CAN.<\/figcaption><\/figure>\n<p>La crise est n\u00e9e. Mais, pour d\u2019autres partenaires du sport roi burkinab\u00e8, le timing ne sied pas. La Coupe d\u2019Afrique des nations se profile \u00e0 l\u2019horizon. Il n\u2019y a pas lieu d\u2019aller en terre d\u2019Eburnie d\u00e9suni. Le pr\u00e9sident du Comit\u00e9 national olympique et des sports burkinab\u00e8 (CNOSB) Singapinda Jean Yam\u00e9ogo joue \u00e0 la m\u00e9diation. Il convoque clubs et FBF dans ce cadre, le lundi 20 novembre dernier. A cette rencontre, la requ\u00eate de la trentaine de clubs est irr\u00e9vocable. Ils veulent la t\u00eate de Lazare Banss\u00e9. La mauvaise gestion de la bourse est mise au-devant pour motiver leur d\u00e9cision.<\/p>\n<p>Ils campent sur leur position et maintiennent leur demande de d\u00e9mission du pr\u00e9sident de la F\u00e9d\u00e9ration pour non-respect de la parole donn\u00e9e. C\u00f4t\u00e9 F\u00e9d\u00e9ration, l\u2019on se plie en excuses pour le manquement de la gestion de l\u2019affaire. Le m\u00e9diateur, lui, demande de la s\u00e9r\u00e9nit\u00e9 avant d\u2019aborder la CAN dans moins de deux mois. Il demande aux frondeurs de laisser passer la CAN pour l&rsquo;int\u00e9r\u00eat sup\u00e9rieur de la nation. Les discussions sont houleuses et les positions tr\u00e8s tranch\u00e9es. Aucun camp ne veut faire de concessions \u00e0 l&rsquo;autre. Finalement, cette rencontre s\u2019est termin\u00e9e en queue de poisson puisqu\u2019elle n\u2019a pas permis d\u2019accorder les violons. Rendez- vous a \u00e9t\u00e9 donn\u00e9 \u00e0 nouveau pour, le mardi 28 novembre prochain avec un espoir de trouver un d\u00e9nouement heureux.<\/p>\n<p style=\"text-align: right\"><strong>Yves OUEDRAOGO <\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019affaire sur les retenues de 25% sur les subventions des clubs revers\u00e9es auTr\u00e9sor public a pris une autre tournure ces derniers jours. D\u00e9sormais, une trentaine de clubs demandent le d\u00e9part du pr\u00e9sident de la F\u00e9d\u00e9ration burkinab\u00e8 de football, Lazare Banss\u00e9. Ce qui a pouss\u00e9 le pr\u00e9sident du Comit\u00e9 national olympique et des sports burkinab\u00e8, Singapinda [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":4180,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[33,19,39],"tags":[],"class_list":{"0":"post-4179","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-actualites","8":"category-football","9":"category-la-une-site"},"jetpack_featured_media_url":"https:\/\/www.sidwaya.info\/sport\/wp-content\/uploads\/sites\/6\/2023\/11\/nouhou.gif","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pamO1T-15p","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/posts\/4179","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/comments?post=4179"}],"version-history":[{"count":0,"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/posts\/4179\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/media\/4180"}],"wp:attachment":[{"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/media?parent=4179"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/categories?post=4179"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/tags?post=4179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}