{"id":4631,"date":"2024-06-13T22:17:57","date_gmt":"2024-06-13T22:17:57","guid":{"rendered":"https:\/\/www.sidwaya.info\/sport\/?p=4631"},"modified":"2024-06-12T22:18:39","modified_gmt":"2024-06-12T22:18:39","slug":"charles-kabore-aux-cotes-des-sportifs-burkinabe-quest-ce-qui-fait-courir-lex-capitaine-des-etalons","status":"publish","type":"post","link":"https:\/\/www.sidwaya.info\/sport\/2024\/06\/13\/charles-kabore-aux-cotes-des-sportifs-burkinabe-quest-ce-qui-fait-courir-lex-capitaine-des-etalons\/","title":{"rendered":"Charles Kabor\u00e9 aux c\u00f4t\u00e9s des sportifs burkinab\u00e8: Qu\u2019est ce qui fait courir l\u2019ex-capitaine des Etalons ?"},"content":{"rendered":"<p>\u00ab C\u2019est juste pour accompagner les sports burkinab\u00e8 en g\u00e9n\u00e9ral. Que ce soit au football ou toutes autres disciplines confondues. Je profite remercier le ministre des Sports, de la Jeunesse et de l\u2019Emploi et le directeur g\u00e9n\u00e9ral du Fonds national pour la promotion du sport et des loisirs pour leur vision. Le sport est un facteur de rassemblement. Il r\u00e9unit tout le monde. Et avoir un esprit sportif est tr\u00e8s important.<\/p>\n<p>Ces deux hommes ont cet esprit de r\u00e9ussite. Je m\u2019associe au d\u00e9veloppement, \u00e0 la bonne vision et \u00e0 l\u2019accompagnement de tous ces sportifs qui se battent pour faire flotter partout dans le monde les couleurs nationales. Pour les Etalons, cela est un peu particulier parce que j\u2019ai eu la chance d\u2019arborer pendant longtemps la tunique de cette \u00e9quipe qui nous est ch\u00e8re. Aujourd\u2019hui, c\u2019est un honneur pour moi d\u2019\u00eatre l\u00e0 et de les encourager. J\u2019ai \u00e9t\u00e9 avec elle au Caire. Je l\u2019ai suivi jusqu\u2019\u00e0 Bamako. Je fais tout cela pour donner le moral \u00e0 mes jeunes fr\u00e8res.<\/p>\n<p>Leur faire comprendre que nous sommes avec eux que ce soit dans les bons ou les difficiles moments. Car, comme on le dit, l\u2019union fait la force. Nous le ferons \u00e0 chaque fois pour peu que notre emploi du temps nous le permette. Je ne suis plus en activit\u00e9 certes. Mais, quand je regarde ce qui se passe, notamment pour les Etalons football, je constate qu\u2019il y a beaucoup de choses derri\u00e8re. Les joueurs, eux, subissent beaucoup, que ce soit dans la positivit\u00e9 que dans la n\u00e9gativit\u00e9, ils prennent des coups.<\/p>\n<p>L\u2019\u00e9quipe actuelle des Etalons est bien jeune et homog\u00e8ne. Nous pr\u00e9parons toujours l\u2019avenir, car, on ne finit jamais d\u2019entreprendre sur ce plan. Avec l\u2019\u00e9quipe que nous avons, j\u2019esp\u00e8re et je crois que nous aurons dans l\u2019avenir de meilleurs r\u00e9sultats. Pour r\u00e9sum\u00e9, je vous dirais que je suis l\u00e0 pour la positivit\u00e9 autour des sports burkinab\u00e8. Nous sommes tous Burkinab\u00e8. Nous sommes li\u00e9s \u00e0 travers le sport que dans la vie courante. Pour cela, il faut que nous soyons porteurs d\u2019un message \u00bb.<\/p>\n<p style=\"text-align: right\"><strong>Propos recueillis par Yves OUEDRAOGO <\/strong><br \/>\n<strong>\u00e0 Bamako<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab C\u2019est juste pour accompagner les sports burkinab\u00e8 en g\u00e9n\u00e9ral. Que ce soit au football ou toutes autres disciplines confondues. Je profite remercier le ministre des Sports, de la Jeunesse et de l\u2019Emploi et le directeur g\u00e9n\u00e9ral du Fonds national pour la promotion du sport et des loisirs pour leur vision. Le sport est un [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":4632,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[33,19,39],"tags":[],"class_list":{"0":"post-4631","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-actualites","8":"category-football","9":"category-la-une-site"},"jetpack_featured_media_url":"https:\/\/www.sidwaya.info\/sport\/wp-content\/uploads\/sites\/6\/2024\/06\/charleskabore.gif","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pamO1T-1cH","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/posts\/4631","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/comments?post=4631"}],"version-history":[{"count":0,"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/posts\/4631\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/media\/4632"}],"wp:attachment":[{"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/media?parent=4631"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/categories?post=4631"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/tags?post=4631"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}