{"id":6689,"date":"2026-02-09T22:36:09","date_gmt":"2026-02-09T22:36:09","guid":{"rendered":"https:\/\/www.sidwaya.info\/sport\/?p=6689"},"modified":"2026-02-09T22:37:43","modified_gmt":"2026-02-09T22:37:43","slug":"fasofoot-ligue-1-18e-journee-rahimo-fc-toujours-invaincu","status":"publish","type":"post","link":"https:\/\/www.sidwaya.info\/sport\/2026\/02\/09\/fasofoot-ligue-1-18e-journee-rahimo-fc-toujours-invaincu\/","title":{"rendered":"Fasofoot Ligue 1\/18e journ\u00e9e:  RAHIMO FC toujours invaincu"},"content":{"rendered":"<p><strong>Du 5 au 8 f\u00e9vrier dernier, le Fasofoot Ligue 1 a livr\u00e9 le verdict de sa 18e journ\u00e9e. Facile vainqueur (3-0) face \u00e0 l\u2019Association sportive du Faso-Yennenga (ASFA-Y), RAHIMO FC demeure invaincu et leader au classement.<\/strong><\/p>\n<p>RAHIMO FC demeure la seule \u00e9quipe invaincue de la saison au Fasofoot Ligue 1. A la faveur de la 18e journ\u00e9e disput\u00e9e du 5 au 8 f\u00e9vrier dernier, les Acad\u00e9miciens de Bama ont enregistr\u00e9 leur 11e victoire de la saison en laminant (3-0) l\u2019Association sportive du Faso Yennenga (ASFA-Y) au stade municipal Issoufou-Joseph-Conombo. Les Buts sont sign\u00e9s Abdoul Rachid Ou\u00e9draogo (26e), Kouassi Mikhael Yamb\u00e9 (50e) et Christophe Ouattara (83e sp). Le choc au sommet entre l\u2019Association sportive des fonctionnaires de Bobo (ASFB) et l\u2019Union sportive des forces arm\u00e9es (USFA) a souri aux Bidasses (4-2).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"6690\" data-permalink=\"https:\/\/www.sidwaya.info\/sport\/2026\/02\/09\/fasofoot-ligue-1-18e-journee-rahimo-fc-toujours-invaincu\/microsoft-word-fasofoot-2-rtf\/\" data-orig-file=\"https:\/\/www.sidwaya.info\/sport\/wp-content\/uploads\/sites\/6\/2026\/02\/Tableau-scaled.jpg\" data-orig-size=\"2556,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;Microsoft Word - Fasofoot 2.rtf&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Microsoft Word &amp;#8211; Fasofoot 2.rtf\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.sidwaya.info\/sport\/wp-content\/uploads\/sites\/6\/2026\/02\/Tableau-1022x1024.jpg\" class=\"wp-image-6690 alignright\" src=\"https:\/\/www.sidwaya.info\/sport\/wp-content\/uploads\/sites\/6\/2026\/02\/Tableau-300x300.jpg\" alt=\"\" width=\"431\" height=\"431\" srcset=\"https:\/\/www.sidwaya.info\/sport\/wp-content\/uploads\/sites\/6\/2026\/02\/Tableau-300x300.jpg 300w, https:\/\/www.sidwaya.info\/sport\/wp-content\/uploads\/sites\/6\/2026\/02\/Tableau-1022x1024.jpg 1022w, https:\/\/www.sidwaya.info\/sport\/wp-content\/uploads\/sites\/6\/2026\/02\/Tableau-150x150.jpg 150w, https:\/\/www.sidwaya.info\/sport\/wp-content\/uploads\/sites\/6\/2026\/02\/Tableau-768x769.jpg 768w, https:\/\/www.sidwaya.info\/sport\/wp-content\/uploads\/sites\/6\/2026\/02\/Tableau-1534x1536.jpg 1534w, https:\/\/www.sidwaya.info\/sport\/wp-content\/uploads\/sites\/6\/2026\/02\/Tableau-2045x2048.jpg 2045w, https:\/\/www.sidwaya.info\/sport\/wp-content\/uploads\/sites\/6\/2026\/02\/Tableau-419x420.jpg 419w, https:\/\/www.sidwaya.info\/sport\/wp-content\/uploads\/sites\/6\/2026\/02\/Tableau-696x697.jpg 696w, https:\/\/www.sidwaya.info\/sport\/wp-content\/uploads\/sites\/6\/2026\/02\/Tableau-1068x1070.jpg 1068w, https:\/\/www.sidwaya.info\/sport\/wp-content\/uploads\/sites\/6\/2026\/02\/Tableau-1920x1923.jpg 1920w\" sizes=\"auto, (max-width: 431px) 100vw, 431px\" \/>Pourtant, ce sont les Buffles de Sikasso-cira qui ont ouvert le score par l\u2019entremise de Cherif Guir\u00e9 (17e). L\u2019USFA r\u00e9tablit la parit\u00e9 gr\u00e2ce \u00e0 Vasseko Kon\u00e9 (28e). Dans sa dynamique, l\u2019\u00e9quipe militaire prend l\u2019avantage coup sur coup gr\u00e2ce \u00e0 un doubl\u00e9 de Abdoulaye Zakou Boubacar (38e et 70e). Les jaune et noir de Bobo-Dioulasso ont r\u00e9duit la marque dans la foul\u00e9e par Akim Ou\u00e9draogo (78e) avant d\u2019encaisser un 4e but sign\u00e9 Ismael Nabelbeda (88e). Ainsi, l\u2019USFA et l\u2019ASFB s\u2019inter-changent leurs positions. Les Bidasses s\u2019invitent au podium et occupent d\u00e9sormais le 3e rang.<\/p>\n<p>Les Buffles quant \u00e0 eux se contentent d\u00e9sormais du pieds du podium. A la r\u00e9ception du Rail club du Kadiogo (RCK), Vitesse FC s\u2019impose par la plus des marques. Gr\u00e2ce \u00e0 cette performance, les Gu\u00e9pards d\u2019Accart-ville quittent la zone de rel\u00e9gation. M\u00eame score en faveur du Sporting FT en d\u00e9placement \u00e0 Bobo-Dioulasso face au Racing club de Bobo (RCB). Tout comme les Tigres de Diarradougou, l\u2019Association des jeunes espoirs de Bobo (AJEB) est tomb\u00e9e (0-1) au stade Wobi face \u00e0 SALITAS FC. Enfin, scores nuls d\u2019un but partout dans les AS Douanes\/SC Majestic et EFO\/CFFEB.<\/p>\n<p style=\"text-align: right\"><strong>Ollo Aim\u00e9 C\u00e9saire HIEN<\/strong><\/p>\n<hr \/>\n<p><strong>Tous les r\u00e9sultats de la journ\u00e9e<\/strong><\/p>\n<p>AS Douanes # SC Majestic\u00a0: 1-1<br \/>\nVitesse FC # RCK\u00a0: 1-0<br \/>\nASFB # USFA\u00a0: 2-4<br \/>\nASFA-Y # RAHIMO FC\u00a0: 0-3<br \/>\nAJEB # SALITAS FC\u00a0: 0-1<br \/>\nAS SONABEL # R\u00e9al du Faso\u00a0: 1-0<br \/>\nRCB # Sporting FT\u00a0: 0-1<br \/>\nEFO # CFFEB\u00a0: 1-1<\/p>\n<p><strong>Meilleur buteur\u00a0:<\/strong> Enouwoklo S\u00e9verin Komi (SC Majestic) 7 buts<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Du 5 au 8 f\u00e9vrier dernier, le Fasofoot Ligue 1 a livr\u00e9 le verdict de sa 18e journ\u00e9e. Facile vainqueur (3-0) face \u00e0 l\u2019Association sportive du Faso-Yennenga (ASFA-Y), RAHIMO FC demeure invaincu et leader au classement. RAHIMO FC demeure la seule \u00e9quipe invaincue de la saison au Fasofoot Ligue 1. A la faveur de la [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":6692,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[33,19,39],"tags":[],"class_list":["post-6689","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualites","category-football","category-la-une-site"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pamO1T-1JT","jetpack_likes_enabled":true,"jetpack_featured_media_url":"https:\/\/www.sidwaya.info\/sport\/wp-content\/uploads\/sites\/6\/2026\/02\/PH-1.jpg","_links":{"self":[{"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/posts\/6689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/comments?post=6689"}],"version-history":[{"count":1,"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/posts\/6689\/revisions"}],"predecessor-version":[{"id":6691,"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/posts\/6689\/revisions\/6691"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/media\/6692"}],"wp:attachment":[{"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/media?parent=6689"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/categories?post=6689"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/tags?post=6689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}