{"id":6693,"date":"2026-02-09T22:53:17","date_gmt":"2026-02-09T22:53:17","guid":{"rendered":"https:\/\/www.sidwaya.info\/sport\/?p=6693"},"modified":"2026-02-09T22:53:17","modified_gmt":"2026-02-09T22:53:17","slug":"fasofoot-ligue-1-as-douanes-majestic-sc-1-1-un-nul-apres-un-duel-de-haute-intensite","status":"publish","type":"post","link":"https:\/\/www.sidwaya.info\/sport\/2026\/02\/09\/fasofoot-ligue-1-as-douanes-majestic-sc-1-1-un-nul-apres-un-duel-de-haute-intensite\/","title":{"rendered":"Fasofoot Ligue 1\/AS Douanes # Majestic SC\u00a0: 1-1 : un nul apr\u00e8s un duel de haute intensit\u00e9"},"content":{"rendered":"<p><strong>Pour le compte de la 18e journ\u00e9e du Fasofoot, l\u2019AS Douanes et Majestic SC se sont neutralis\u00e9s (1-1), le samedi 7 f\u00e9vrier 2026, au stade Municipal Issoufou-Joseph-Conombo. Si les Gabelous ont longtemps men\u00e9 au score, ils ont fini par craquer dans les derniers instants face \u00e0 des Acad\u00e9miciens persistants.<\/strong><\/p>\n<p>Le duel entre les Gabelous de Yaya Kon\u00e9 et les Acad\u00e9miciens de Moussa Sanogo, dit \u00ab Falcao \u00bb, a tenu toutes ses promesses en termes d\u2019intensit\u00e9. Revancharde apr\u00e8s la claque re\u00e7ue au match-aller (0-3), l\u2019AS Douanes a affich\u00e9 ses intentions d\u00e8s l\u2019entame de la rencontre. Pourtant, c\u2019est Majestic qui prend d&rsquo;abord le contr\u00f4le du jeu, imposant sa patte sur la possession de balle. Malgr\u00e9 cette domination territoriale des Acad\u00e9miciens, la d\u00e9fense de Majestic montre des signes de f\u00e9brilit\u00e9. A la 15e minute, apr\u00e8s une alerte chaude de Mohamed Lamine Traor\u00e9 dont la frappe est d\u00e9tourn\u00e9e en corner, la sentence tombe.<\/p>\n<p>Le capitaine des Gabelous, Hanaby Hadalou Sagn\u00e9, plus prompt sur le coup de pied de coin, ouvre le score et lib\u00e8re les siens. Piqu\u00e9 au vif, Falcao d\u00e9cide de r\u00e9agir tactiquement avant m\u00eame la pause. A la 39e minute, Abdoul Rachid Traor\u00e9 c\u00e8de sa place \u00e0 Nouhan David Diallo pour redynamiser son milieu offensif. Un coaching qui a failli payer imm\u00e9diatement. En effet, \u00e0 la 40e, Joseph Lucky Mamodu doit s\u2019employer d&rsquo;une parade magistrale pour sortir une t\u00eate crois\u00e9e de Junior Kafando. Toutefois, c\u2019est l\u2019AS Douanes qui s\u2019offre la derni\u00e8re occasion de la premi\u00e8re partie. Juste avant de regagner les vestiaires, Mohamed Lamine Traor\u00e9 manque l\u2019occasion du KO pour son \u00e9quipe, mais a p\u00e9ch\u00e9 par exc\u00e8s d&rsquo;attentisme dans la surface. Au retour de la pause, le sc\u00e9nario reste identique. Mohamed Lamine Traor\u00e9, encore lui, h\u00e9rite d&rsquo;un caviar dans le dos de la d\u00e9fense \u00e0 la 50e, mais envoie le cuir dans les nuages alors qu&rsquo;il \u00e9tait seul face au but. Un manque de r\u00e9alisme que les Gabelous vont finir par regretter.<\/p>\n<p>Alors que l&rsquo;on s&rsquo;acheminait vers une victoire de l&rsquo;AS Douanes, le coaching de Falcao finit par porter ses fruits. A la 87e minute, Abdoul Aziz Kongo, entr\u00e9 en cours de jeu, profite d&rsquo;une situation confuse pour placer une reprise. Le ballon, presque avec nonchalance, roule lentement pour mourir au fond des filets (1-1). Les sept minutes de temps additionnel n&rsquo;y changeront rien, malgr\u00e9 un chass\u00e9-crois\u00e9 \u00e9lectrique entre les deux camps. Majestic SC conserve sa place sur le podium avec 31 points, tandis que l\u2019AS Douanes (24 points) pourra nourrir d&rsquo;\u00e9normes regrets apr\u00e8s avoir men\u00e9 pendant 72 minutes.<\/p>\n<p style=\"text-align: right\"><strong>Pengdwend\u00e9 Achille OUEDRAOGO<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pour le compte de la 18e journ\u00e9e du Fasofoot, l\u2019AS Douanes et Majestic SC se sont neutralis\u00e9s (1-1), le samedi 7 f\u00e9vrier 2026, au stade Municipal Issoufou-Joseph-Conombo. Si les Gabelous ont longtemps men\u00e9 au score, ils ont fini par craquer dans les derniers instants face \u00e0 des Acad\u00e9miciens persistants. Le duel entre les Gabelous de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":6694,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[33],"tags":[],"class_list":["post-6693","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualites"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pamO1T-1JX","jetpack_likes_enabled":true,"jetpack_featured_media_url":"https:\/\/www.sidwaya.info\/sport\/wp-content\/uploads\/sites\/6\/2026\/02\/Action.jpeg","_links":{"self":[{"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/posts\/6693","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/comments?post=6693"}],"version-history":[{"count":1,"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/posts\/6693\/revisions"}],"predecessor-version":[{"id":6695,"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/posts\/6693\/revisions\/6695"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/media\/6694"}],"wp:attachment":[{"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/media?parent=6693"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/categories?post=6693"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/tags?post=6693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}