{"id":6717,"date":"2026-02-18T00:34:34","date_gmt":"2026-02-18T00:34:34","guid":{"rendered":"https:\/\/www.sidwaya.info\/sport\/?p=6717"},"modified":"2026-02-18T00:36:37","modified_gmt":"2026-02-18T00:36:37","slug":"ba-banien-sirima-la-voix-burkinabe-du-handball-africain","status":"publish","type":"post","link":"https:\/\/www.sidwaya.info\/sport\/2026\/02\/18\/ba-banien-sirima-la-voix-burkinabe-du-handball-africain\/","title":{"rendered":"Ba-Banien Sirima: la voix burkinab\u00e8 du handball africain"},"content":{"rendered":"<p><strong>Nomm\u00e9 membre de la commission entrainements et m\u00e9thodes de la Conf\u00e9d\u00e9ration africaine de handball (CAHB) pour la mandature 2025-2029, le Directeur technique national (DTN) de la F\u00e9d\u00e9ration burkinab\u00e8 de handball (FBHB), Ba-Banien Sirima, voit dans cette d\u00e9signation une reconnaissance du travail accompli au Burkina Faso. Dans cet entretien, il revient sur la port\u00e9e de cette nomination et ses ambitions pour le d\u00e9veloppement du handball national et continental.<\/strong><\/p>\n<p><strong>Pouvez-vous vous pr\u00e9senter \u00e0 nos lecteurs ?<\/strong><\/p>\n<p>Je suis agent au minist\u00e8re des Sports, de la Jeunesse et de l\u2019Emploi, entra\u00eeneur de handball et actuellement Directeur technique national de la F\u00e9d\u00e9ration burkinab\u00e8 de handball.<br \/>\nAncien joueur, j\u2019ai d\u00e9couvert le handball \u00e0 l\u2019\u00e9cole \u00e0 travers les comp\u00e9titions scolaires. Tr\u00e8s t\u00f4t, je me suis passionn\u00e9 pour l\u2019encadrement. En 1999, j\u2019ai int\u00e9gr\u00e9 l\u2019Institut des sciences du sport o\u00f9 j\u2019ai poursuivi ma formation. J\u2019ai ensuite cr\u00e9\u00e9 une \u00e9cole de handball, que j\u2019ai mise au service de mon club, l\u2019AS SONABHY. Apr\u00e8s avoir arr\u00eat\u00e9 officiellement ma carri\u00e8re de joueur en 2010, je me suis consacr\u00e9 enti\u00e8rement \u00e0 l\u2019encadrement. J\u2019ai occup\u00e9 successivement les postes d\u2019entra\u00eeneur national adjoint, s\u00e9lectionneur des jeunes, s\u00e9lectionneur senior, avant d\u2019\u00eatre nomm\u00e9 DTN.<\/p>\n<p><strong>Quel a \u00e9t\u00e9 votre sentiment \u00e0 l\u2019annonce de votre nomination au sein de la commission entra\u00eenements et m\u00e9thodes de la Conf\u00e9d\u00e9ration africaine de handball (CAHB) ?<\/strong><\/p>\n<p>C\u2019est un sentiment de grande fiert\u00e9. Cette commission est directement li\u00e9e \u00e0 mes missions actuelles de DTN. Etre choisi pour repr\u00e9senter la Zone 3 au niveau continental est une<br \/>\nmarque de confiance. Cela signifie que le travail accompli au niveau national est reconnu. C\u2019est un honneur, mais aussi une lourde responsabilit\u00e9.<\/p>\n<p><strong>Au-del\u00e0 de votre personne, que repr\u00e9sente cette nomination pour le Burkina Faso et la FBHB ?<\/strong><\/p>\n<p>C\u2019est une avanc\u00e9e importante. Il est essentiel pour un pays d\u2019\u00eatre repr\u00e9sent\u00e9 dans les instances continentales. Cela permet de mieux comprendre les orientations strat\u00e9giques, de d\u00e9fendre ses int\u00e9r\u00eats et de participer aux prises de d\u00e9cisions.<br \/>\nLe Burkina Faso n\u2019est pas toujours suffisamment repr\u00e9sent\u00e9 dans certaines sph\u00e8res sportives africaines. Cette pr\u00e9sence est donc une opportunit\u00e9 pour valoriser notre savoir-faire et partager notre exp\u00e9rience, notamment notre capacit\u00e9 \u00e0 obtenir des r\u00e9sultats avec des moyens limit\u00e9s.<\/p>\n<h3>Quelles sont les missions de cette commission ?<\/h3>\n<p>La commission, entrainements et m\u00e9thodes s\u2019occupe de tout ce qui touche \u00e0 l\u2019encadrement technique : la formation des entraineurs, les contenus p\u00e9dagogiques, la planification, les<br \/>\nlicences et la mise en conformit\u00e9 avec les r\u00e9formes de la F\u00e9d\u00e9ration internationale. Aujourd\u2019hui, il existe des exigences pr\u00e9cises pour diriger une \u00e9quipe en comp\u00e9tition officielle.<\/p>\n<p>Notre r\u00f4le sera d\u2019accompagner les f\u00e9d\u00e9rations dans la mise \u00e0 niveau de leurs entra\u00eeneurs et dans l\u2019harmonisation des standards techniques sur le continent.<\/p>\n<p><strong>Quels sont les chantiers prioritaires pour am\u00e9liorer le niveau des entra\u00eeneurs africains ?<\/strong><\/p>\n<p>Il faut renforcer l\u2019acc\u00e8s aux formations certifiant, harmoniser les contenus p\u00e9dagogiques et faciliter les \u00e9changes d\u2019expertise entre les zones. Plusieurs pays accusent un retard dans la mise \u00e0 jour des dipl\u00f4mes. Il est important de r\u00e9duire ces \u00e9carts pour \u00e9lever globalement le niveau du handball africain.<\/p>\n<p><strong>Comment concilierez-vous vos fonctions nationales et cette mission continentale ?<\/strong><\/p>\n<p>La mission ne n\u00e9cessite pas un changement de r\u00e9sidence. Le travail se fera principalement en ligne, avec quelques missions ponctuelles. J\u2019ai toujours su concilier mes responsabilit\u00e9s administratives et techniques. Cette nouvelle fonction viendra enrichir mon action au niveau national.<\/p>\n<p><strong>Concr\u00e8tement, comment le handball burkinab\u00e8 pourra-t-il tirer profit de votre pr\u00e9sence \u00e0 la CAHB ?<\/strong><\/p>\n<p>Nous aurons un acc\u00e8s plus direct aux informations strat\u00e9giques et aux opportunit\u00e9s de formation. Le handball burkinab\u00e8 reste fortement scolaire et universitaire. Nous<br \/>\nfaisons face \u00e0 un d\u00e9ficit d\u2019infrastructures et de mat\u00e9riel. Notre priorit\u00e9 est la formation \u00e0 la base et la mise \u00e0 niveau rapide des entra\u00eeneurs, surtout ceux appel\u00e9s \u00e0 encadrer les \u00e9quipes nationales. Les nouvelles r\u00e9glementations exigent des dipl\u00f4mes sp\u00e9cifiques pour diriger une \u00e9quipe en comp\u00e9tition officielle. Nous devons nous conformer \u00e0 ces standards.<\/p>\n<p>Cette nomination facilitera-t-elle l\u2019organisation de stages ou l\u2019obtention de bourses ?<\/p>\n<p>Des actions sont d\u00e9j\u00e0 engag\u00e9es. En 2026, une formation pour l\u2019obtention d\u2019une licence internationale de base est programm\u00e9e. Nous travaillons \u00e9galement \u00e0 envoyer certains<br \/>\nentra\u00eeneurs se former dans la sous-r\u00e9gion afin d\u2019augmenter rapidement le nombre de techniciens qualifi\u00e9s. Si des opportunit\u00e9s suppl\u00e9mentaires se pr\u00e9sentent gr\u00e2ce \u00e0 la CAHB,<br \/>\nnous les saisirons au b\u00e9n\u00e9fice de nos encadreurs.<\/p>\n<p><strong>Quels sont vos objectifs personnels pour ce mandat ?<\/strong><\/p>\n<p>La r\u00e9ussite. Cette nomination repose sur une confiance accord\u00e9e \u00e0 ma personne et \u00e0 mon pays. Je souhaite contribuer \u00e0 moderniser les m\u00e9thodes d\u2019entra\u00eenement et \u00e0 renforcer la<br \/>\nprofessionnalisation des entra\u00eeneurs sur le continent.<\/p>\n<p><strong>Quel est votre message \u00e0 la famille du handball burkinab\u00e8 ?<\/strong><\/p>\n<p>Je f\u00e9licite tous les encadreurs pour leur engagement, souvent b\u00e9n\u00e9vole, malgr\u00e9 des moyens limit\u00e9s. Je les encourage \u00e0 pers\u00e9v\u00e9rer et surtout \u00e0 se former. L\u2019avenir du handball<br \/>\nburkinab\u00e8 d\u00e9pendra de notre capacit\u00e9 \u00e0 investir dans nos comp\u00e9tences. C\u2019est \u00e0 nous de tracer la voie pour les g\u00e9n\u00e9rations futures.<\/p>\n<p style=\"text-align: right\"><strong>Pengdwend\u00e9 Achille OUEDRAOGO<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nomm\u00e9 membre de la commission entrainements et m\u00e9thodes de la Conf\u00e9d\u00e9ration africaine de handball (CAHB) pour la mandature 2025-2029, le Directeur technique national (DTN) de la F\u00e9d\u00e9ration burkinab\u00e8 de handball (FBHB), Ba-Banien Sirima, voit dans cette d\u00e9signation une reconnaissance du travail accompli au Burkina Faso. Dans cet entretien, il revient sur la port\u00e9e de cette [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":6719,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[33,29,39],"tags":[],"class_list":["post-6717","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualites","category-autres-sports","category-la-une-site"],"jetpack_featured_media_url":"https:\/\/www.sidwaya.info\/sport\/wp-content\/uploads\/sites\/6\/2026\/02\/Sirima-copie.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pamO1T-1Kl","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/posts\/6717","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/comments?post=6717"}],"version-history":[{"count":1,"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/posts\/6717\/revisions"}],"predecessor-version":[{"id":6718,"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/posts\/6717\/revisions\/6718"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/media\/6719"}],"wp:attachment":[{"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/media?parent=6717"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/categories?post=6717"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/tags?post=6717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}