{"id":6739,"date":"2026-02-25T23:53:25","date_gmt":"2026-02-25T23:53:25","guid":{"rendered":"https:\/\/www.sidwaya.info\/sport\/?p=6739"},"modified":"2026-02-25T23:56:27","modified_gmt":"2026-02-25T23:56:27","slug":"le-jeune-du-ramadan-et-le-sport-de-haut-niveau-les-conseils-du-dr-wendsendate-yves-sempore","status":"publish","type":"post","link":"https:\/\/www.sidwaya.info\/sport\/2026\/02\/25\/le-jeune-du-ramadan-et-le-sport-de-haut-niveau-les-conseils-du-dr-wendsendate-yves-sempore\/","title":{"rendered":"Le je\u00fbne du Ramadan et le sport de haut niveau:  les conseils du Dr Wends\u00e8ndat\u00e9 Yves Sempor\u00e9"},"content":{"rendered":"<p><strong>Les fid\u00e8les musulmans du Burkina Faso et du monde observent depuis quelques jours, le je\u00fbne du mois de Ramadan, l\u2019un des cinq piliers de l\u2019Islam qui les oblige \u00e0 se priver de boissons et de nourriture toute la journ\u00e9e. Il se pose alors chaque ann\u00e9e une question qui suscite un grand int\u00e9r\u00eat et de gros d\u00e9bats au sein des milieux sportifs : la compatibilit\u00e9 du je\u00fbne avec le sport de haut niveau. C\u2019est ce sujet qu\u2019aborde dans cet entretien le Dr Wends\u00e8ndat\u00e9 Yves Sempor\u00e9, M\u00e9decin du sport et Enseignant Hospitalo-universitaire en Physiologie humaine \u00e0 l\u2019Universit\u00e9 Nazi-Boni de Bobo-Dioulasso.<\/strong><\/p>\n<p>Docteur, d\u2019un point de vue m\u00e9dical, comment d\u00e9finissez-vous les principaux changements<br \/>\nphysiologiques li\u00e9s au je\u00fbne du Ramadan ?<\/p>\n<p>Tout d\u2019abord je vous remercie pour cette opportunit\u00e9 de parler d\u2019un sujet d\u2019actualit\u00e9 en lien avec le sport et le je\u00fbne du Ramadan. En effet, au cours du je\u00fbne du Ramadan les pratiquants se privent de toute prise alimentaire et hydrique depuis l\u2019aurore jusqu\u2019au cr\u00e9puscule. Cela entraine d\u2019embl\u00e9e un changement sur la disponibilit\u00e9 des substrats \u00e9nerg\u00e9tiques notamment glucidiques (sucre) qui tendent \u00e0 s\u2019\u00e9puiser au cours de la journ\u00e9e. Pourtant les glucides sont la principale source de notre organisme pour les efforts physiques. Aussi, nous avons une perturbation du bilan de l\u2019eau et des \u00e9lectrolytes (min\u00e9raux) dans l\u2019organisme avec un risque de d\u00e9shydration du fait de l\u2019absence de consommation d\u2019eau. A tout cela s\u2019ajoute un changement non moindre qui est la perturbation du sommeil, car, les pratiquants du je\u00fbne sont amen\u00e9s \u00e0 se r\u00e9veiller plus t\u00f4t le matin et \u00e0 manger le principal repas de la journ\u00e9e le soir ce qui peut alt\u00e9rer la dur\u00e9e et la qualit\u00e9 du sommeil. Les deux premiers types de changements \u00e9voqu\u00e9s pr\u00e9c\u00e9demment seront plus ou moins s\u00e9v\u00e8res suivant les individus, les activit\u00e9s men\u00e9es durant la p\u00e9riode \u00e0 jeun et le climat, notamment la temp\u00e9rature ambiante.<\/p>\n<p><strong>Le je\u00fbne du Ramadan est-il compatible avec le sport de haut niveau ?<\/strong><\/p>\n<p>Le sport de haut niveau est tr\u00e8s exigeant en termes de besoins \u00e9nerg\u00e9tiques et hydriques. Cela est d\u2019autant plus vrai dans le contexte des pays \u00e0 climat tropical comme le n\u00f4tre avec des temp\u00e9ratures avoisinant 35\u00b0 dans l\u2019apr\u00e8s-midi. Le je\u00fbne est donc une contrainte importante et un stress psycho-physiologique suppl\u00e9mentaire pour le sportif de haut niveau qui pratique son sport dans cette p\u00e9riode. Il doit en \u00eatre conscient afin de faire des ajustements strat\u00e9giques rigoureux pour que cela n\u2019entache pas trop sa performance sportive mais aussi sa sant\u00e9 \u00e0 court, moyen et long terme.<\/p>\n<p><strong>Existe-t-il des profils d\u2019athl\u00e8tes pour lesquels le je\u00fbne est plus contraignant ?<\/strong><\/p>\n<p>Oui bien s\u00fbr ! Consid\u00e9rant l\u2019\u00e2ge en raison de la faible masse corporelle, les sportifs des petites cat\u00e9gories (minimes, cadets, juniors) auront plus de difficult\u00e9s \u00e0 compenser les effets du je\u00fbne et seront plus \u00e0 risque de d\u00e9shydratation et de manque d\u2019\u00e9nergie. Le manque de substrats \u00e9nerg\u00e9tiques glucidiques li\u00e9 au je\u00fbne affectera aussi beaucoup plus les athl\u00e8tes des sports de puissance comme l\u2019halt\u00e9rophilie et la course de vitesse pour ne citer qu\u2019eux. Dans ces types de sports, la source d\u2019\u00e9nergie est quasi exclusivement les glucides (sucre). Dans notre jargon nous disons qu\u2019ils auront une baisse de la capacit\u00e9 ana\u00e9robie. Cependant dans des sports d\u2019endurance comme le football, les sportifs peuvent \u00eatre surtout affect\u00e9s pour gestes sportifs qui demandent de la puissance (tir, acc\u00e9l\u00e9rations r\u00e9p\u00e9t\u00e9es, etc.). La d\u00e9shydratation, quant \u00e0 elle, sera contraignante pour tous les athl\u00e8tes de fa\u00e7on g\u00e9n\u00e9rale, mais plus sp\u00e9cifiquement dans les sports d\u2019endurance et chez les athl\u00e8tes de sexe f\u00e9minin.<\/p>\n<p><strong>Pourquoi les athl\u00e8tes de sexe f\u00e9minin ?<\/strong><\/p>\n<p>Parce que pour un m\u00eame poids corporel, la femme a physiologiquement une proportion d\u2019eau totale inferieure \u00e0 celle de l\u2019homme. Ce qui augmente encore le risque de d\u00e9shydratation.<\/p>\n<p><strong>Y a-t-il un avantage pour un sportif en comp\u00e9tition d\u2019observer le je\u00fbne ?<\/strong><\/p>\n<p>Le je\u00fbne est plus adapt\u00e9 \u00e0 l\u2019entra\u00eenement qu\u2019\u00e0 la comp\u00e9tition intense. Il peut aider le sportif dans l\u2019adaptation de son m\u00e9tabolisme (comment son corps produit l\u2019\u00e9nergie n\u00e9cessaire pour l\u2019effort physique) \u00e0 utiliser par exemple plus de graisses pour produire de l\u2019\u00e9nergie mais c\u2019est trop \u00ab technique \u00bb \u00e0 d\u00e9velopper ici, ou pour perdre du poids dans le cadre des sports de cat\u00e9gorie de poids.<\/p>\n<p><strong>Quel est l\u2019impact du je\u00fbne du Ramadan sur la performance des sportifs ?<\/strong><\/p>\n<p>Dans notre contexte, il y a un risque r\u00e9el de baisse de la performance du sportif. L\u2019absence d\u2019apport \u00e9nerg\u00e9tique alimentaire augmente le risque d\u2019hypoglyc\u00e9mie, entraine une baisse de la vigilance et alt\u00e8re la pr\u00e9cision des mouvements. Aussi, une mauvaise qualit\u00e9 du sommeil va jouer sur la \u00ab fra\u00eecheur physique \u00bb m\u00eame du sportif.<\/p>\n<p>Cependant, le v\u00e9ritable ennemi de la performance sportive est la d\u00e9shydratation. En climat chaud, la d\u00e9shydratation entraine une baisse des comp\u00e9tences techniques, de la capacit\u00e9 d\u2019endurance et de la concentration. Les \u00e9tudes scientifiques<\/p>\n<p>s\u2019accordent \u00e0 dire qu\u2019une perte de 1% de son poids en eau entraine une baisse des r\u00e9flexes de jeu et de la capacit\u00e9 \u00e0 r\u00e9fl\u00e9chir pour bien jouer. Une perte de 2% du poids en eau soit environ 1,4 l d\u2019eau pour un athl\u00e8te de 70 Kg entraine une baisse de 20% de ses capacit\u00e9s physiques. Quand cette perte atteint 4%, ce qui peut arriver dans le cadre du je\u00fbne en climat tr\u00e8s chaud, cela est vraiment dangereux avec toutes les fonctions de l\u2019organisme qui sont touch\u00e9es avec un risque de coup de chaleur d\u2019effort ou d\u2019hyperthermie d\u2019effort qui peuvent \u00eatre mortels.<\/p>\n<p><strong>Le risque de blessure augmente-t-il pendant cette p\u00e9riode ?<\/strong><\/p>\n<p>L\u2019absence d\u2019apports hydriques pendant l\u2019effort physique prolong\u00e9 et la d\u00e9shydratation entrainent une augmentation des blessures musculaires et ligamentaires chez le sportif. On note aussi une fr\u00e9quence plus \u00e9lev\u00e9e des crampes musculaires.<\/p>\n<p><strong>Dans le contexte du championnat D1 de football, les matchs jou\u00e9s en fin d\u2019apr\u00e8s-midi posent-ils un risque m\u00e9dical particulier ?<\/strong><\/p>\n<p>Oui cela pose un risque m\u00e9dical li\u00e9 \u00e0 la d\u00e9shydratation pour les footballeurs qui pratiquent le je\u00fbne le jour de match. En effet, il fait chaud \u00e0 15h30 qui est l\u2019horaire habituelle de d\u00e9but de nos matchs de D1. Pour un joueur qui n\u2019a pas bu de l\u2019eau depuis le matin, et qui ne va n\u2019ont plus s\u2019hydrater pendant le match, la d\u00e9shydratation est in\u00e9vitable. Je vous ai pr\u00e9c\u00e9demment d\u00e9crit les dangers de la d\u00e9shydratation pour le sportif, il s\u2019y expose donc.<\/p>\n<p><strong>Quelles sont les attitudes que doivent prendre ceux qui d\u00e9cident n\u00e9anmoins de je\u00fbner ?<\/strong><\/p>\n<p>Dans notre contexte, je d\u00e9conseille le je\u00fbne les jours de match par exemple. Cependant, au vu de la n\u00e9cessit\u00e9 de concilier foi et performance, pour ceux qui d\u00e9cident n\u00e9anmoins de je\u00fbner je pr\u00e9conise pour le repas du soir de mettre l\u2019accent sur des repas \u00e0 base de sucres lents (riz, t\u00f4t), de bien s\u2019hydrater en buvant beaucoup d\u2019eau.<\/p>\n<p>Le matin il est souvent difficile de beaucoup manger, mais ils doivent faire l\u2019effort de manger encore des aliments riches en sucre accompagn\u00e9s d\u2019une bonne quantit\u00e9 d\u2019eau. Aussi, ils doivent faire attention et rester dans un environnement assez frais et limiter leurs activit\u00e9s dans la journ\u00e9e pour limiter la d\u00e9shydratation, jusqu\u2019\u00e0 l\u2019heure du match ou de l\u2019entrainement.<\/p>\n<p>Au-del\u00e0 de tout \u00e7a, le joueur doit \u00eatre attentif \u00e0 son corps et pr\u00e9venir le staff m\u00e9dical qu\u2019il a je\u00fbn\u00e9. En effet, tout sympt\u00f4me au cours de l\u2019effort (vertiges, maux de t\u00eate, fatigue exag\u00e9r\u00e9e, tremblement, douleur \u00e0 la poitrine, une intol\u00e9rance inhabituelle de l\u2019effort) doit l\u2019amener imm\u00e9diatement \u00e0 arr\u00eater le match et les efforts physiques. Voici quelques conseils que je peux donner.<\/p>\n<p><strong>Quels conseils avez-vous \u00e0 donner aux entraineurs du championnat<\/strong><\/p>\n<p>burkinab\u00e8 qui se d\u00e9roule actuellement, \u00e0 cette p\u00e9riode de je\u00fbne,<br \/>\nsurtout que tous les matchs se d\u00e9roulent dans l\u2019apr\u00e8s-midi et non en soir\u00e9e ?<br \/>\nAux entraineurs et en ce qui concerne les entrainements, selon les capacit\u00e9s du club et si possible, il faut programmer durant le Ramadan une s\u00e9ance d\u2019entrainement unique assez t\u00f4t le matin ou le soir apr\u00e8s la rupture du je\u00fbne.<\/p>\n<p>Les jours de match, l\u2019entraineur doit identifier les joueurs qui font le je\u00fbne et surveiller avec la complicit\u00e9 du staff m\u00e9dical leur attitude et la performance depuis l\u2019\u00e9chauffement et tout au long du jeu, pour d\u00e9celer pr\u00e9cocement des signes de danger et proc\u00e9der \u00e0 des changements \u00e0 temps.<br \/>\nApr\u00e8s les matchs, ils peuvent avec l\u2019aide du staff m\u00e9dical, encourager les joueurs \u00e0 une bonne alimentation et \u00e0 une bonne r\u00e9hydratation pour favoriser la r\u00e9cup\u00e9ration.<\/p>\n<p style=\"text-align: right\">Entretien r\u00e9alis\u00e9 par<br \/>\n<strong>Si\u00e9 Simplice HIEN<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les fid\u00e8les musulmans du Burkina Faso et du monde observent depuis quelques jours, le je\u00fbne du mois de Ramadan, l\u2019un des cinq piliers de l\u2019Islam qui les oblige \u00e0 se priver de boissons et de nourriture toute la journ\u00e9e. Il se pose alors chaque ann\u00e9e une question qui suscite un grand int\u00e9r\u00eat et de gros [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":6741,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[33,29,39,37],"tags":[],"class_list":["post-6739","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualites","category-autres-sports","category-la-une-site","category-sport"],"jetpack_featured_media_url":"https:\/\/www.sidwaya.info\/sport\/wp-content\/uploads\/sites\/6\/2026\/02\/ITW-Yves-Sempore.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pamO1T-1KH","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/posts\/6739","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/comments?post=6739"}],"version-history":[{"count":1,"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/posts\/6739\/revisions"}],"predecessor-version":[{"id":6740,"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/posts\/6739\/revisions\/6740"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/media\/6741"}],"wp:attachment":[{"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/media?parent=6739"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/categories?post=6739"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/tags?post=6739"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}