{"id":6855,"date":"2026-04-13T22:47:52","date_gmt":"2026-04-13T22:47:52","guid":{"rendered":"https:\/\/www.sidwaya.info\/sport\/?p=6855"},"modified":"2026-04-13T22:48:47","modified_gmt":"2026-04-13T22:48:47","slug":"24-minutes-de-feu-de-landry-kabore","status":"publish","type":"post","link":"https:\/\/www.sidwaya.info\/sport\/2026\/04\/13\/24-minutes-de-feu-de-landry-kabore\/","title":{"rendered":"24 minutes de feu de Landry Kabor\u00e9"},"content":{"rendered":"<p><strong>Les bonnes performances de Pierre Landry Kabor\u00e9 et Edmond Tapsoba, sans oublier le probable titre de champion de Kilian Niki\u00e8ma sont entre autres bonnes nouvelles du weekend pour les footballeurs burkinab\u00e8 expatri\u00e9s. <\/strong><\/p>\n<p>Entr\u00e9 en jeu \u00e0 la 66e, 24 minutes ont suffit \u00e0 Pierre Landry Kabor\u00e9 (24 ans, 20 matchs, 5 buts) pour faire basculer le cours de l\u2019opposition de la 33e lev\u00e9e du championnat \u00e9cossais entre Motherwell et Hearts (1er). Alors que son club \u00e9tait men\u00e9, il a d\u2019abord provoqu\u00e9 un penalty (87e) avant de sceller le sort de la rencontre (90+2) pour une victoire 3-1. Il a \u00e9t\u00e9 d\u00e9sign\u00e9 en toute logique, homme du match. Dans ce marathon, le mano \u00e0 mano entre Hearts et Rangers (2e) de Nasser Djiga (23 ans, 20 matchs) sera jusqu\u2019au bout. Car, les Rangers, 2e au classement \u00e0 un point du leader Hearts sont all\u00e9s faire d\u2019une bouch\u00e9e Falkirk FC 3-6. Match disput\u00e9 dans son enti\u00e8ret\u00e9 par Djiga.<\/p>\n<p>La grande sensation de la 29e journ\u00e9e de la Bundesliga est venue du Signal Iduna Park de Dortmund, o\u00f9, le Bayer Leverkusen (5e) amen\u00e9 par un Edmond Tapsoba (27 ans, 24 matchs, 5 buts) des grands jours a battu l\u2019\u00e9quipe locale 0-1. En d\u00e9placement sur les installations de Mayence, le club, Fribourg (8e) de l\u2019autre Burkinab\u00e8 de ce championnat, Cyriaque Iri\u00e9 (20 ans, 9 matchs) align\u00e9 d\u2019entr\u00e9e (puis remplac\u00e9 \u00e0 la 64e) s\u2019est offert 3 pr\u00e9cieux points suite \u00e0 sa victoire 0-1. Brentford (7e) avec Aboubacar Dango Ouattara (24 ans, 26 matchs, 5 buts) se sont laiss\u00e9s rattraper au score (2-2) par Everton en 32e journ\u00e9e du Premier anglais. Issa Kabor\u00e9 (24 ans, 26 matchs) dans le m\u00eame pays mais dans la division inferieure (D2, 42e journ\u00e9e) et son \u00e9quipe Wrexham (7e) sont tomb\u00e9s \u00e0 Birmingham 2-0. Kilian Niki\u00e8ma presque s\u00fbr d\u2019\u00eatre champion Dans la Ligue 1 fran\u00e7aise (29e journ\u00e9e), Lyon a eu raison 2-0 de Lorient (9e) et Ars\u00e8ne Kouassi (21 ans, 27 matchs, 2 buts) remplac\u00e9 \u00e0 la 73e.<\/p>\n<p>C\u2019est aussi une d\u00e9faite que Angers (13e) a conc\u00e9d\u00e9 \u00e0 Rennes 2-1. Comme cela est de coutume, c\u2019est Herv\u00e9 Koffi (29 ans, 25 matchs) qui \u00e9tait dans les poteaux angevins. OB (2e) \u00e0 l\u2019occasion de la Super division pour le maintien dans l\u2019\u00e9lite danoise est tomb\u00e9 devant Silkeborg IF 3-1. Ismahila Ou\u00e9draogo (26 ans, 20 matchs) pour l\u2019occasion est sorti \u00e0 la 82e. Arthur Zagr\u00e9 (24 ans, 26 matchs, 3 buts) et les siens de Excelsior (15e) ont fait mieux en cette 30e journ\u00e9e du championnat hollandais. Avec le gaucher nominal burkinab\u00e8 titulaire, l\u2019\u00e9quipe est all\u00e9e tenir en \u00e9chec (2-2) Zwolle. En Russie (24e journ\u00e9e), Mohamed Konat\u00e9 (28 ans, 16 matchs, 1 but) n\u2019a b\u00e9n\u00e9fici\u00e9 que d\u2019une dizaine de minutes de temps de jeu lors du partage des points entre Krylya Sovetov Samara et Akhmat (9e).<\/p>\n<p>Malgr\u00e9 leur d\u00e9faite 1-0 face \u00e0 Dordrecht, ADO et son portier international burkinab\u00e8 Kilian Niki\u00e8ma (22 ans, 35 matchs) sont presque s\u00fbrs d\u2019\u00eatre parmi les \u00e9quipes de la comp\u00e9tition d\u2019\u00e9lite la saison \u00e0 venir. Avec 8 points d\u2019\u00e9cart sur son poursuivant direct \u00e0 3 journ\u00e9es de la fin du championnat D2 hollandais, ADO sauf miracle devrait terminer champion. Dans le MLS am\u00e9ricain (7e journ\u00e9e), Ouss\u00e9ni Bouda (25 ans, 7 matchs, 2 buts) a disput\u00e9 l\u2019enti\u00e8ret\u00e9 de la rencontre victorieuse 1-3 de San Jose (2e) sur Kansas City. L\u2019autre Burkinab\u00e8 de ce championnat Georgi Minoungou (23 ans) a fait ses d\u00e9buts sous ses nouvelles couleurs de Colorado Rapids (8e) par une passe d\u00e9cisive (73e) lors de leur victoire 6-2 sur Houston.<\/p>\n<p style=\"text-align: right\"><strong>Yves OUEDRAOGO <\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les bonnes performances de Pierre Landry Kabor\u00e9 et Edmond Tapsoba, sans oublier le probable titre de champion de Kilian Niki\u00e8ma sont entre autres bonnes nouvelles du weekend pour les footballeurs burkinab\u00e8 expatri\u00e9s. Entr\u00e9 en jeu \u00e0 la 66e, 24 minutes ont suffit \u00e0 Pierre Landry Kabor\u00e9 (24 ans, 20 matchs, 5 buts) pour faire basculer [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":6856,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[19,39,37],"tags":[],"class_list":["post-6855","post","type-post","status-publish","format-standard","has-post-thumbnail","category-football","category-la-une-site","category-sport"],"jetpack_featured_media_url":"https:\/\/www.sidwaya.info\/sport\/wp-content\/uploads\/sites\/6\/2026\/04\/Landry-1.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pamO1T-1Mz","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/posts\/6855","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/comments?post=6855"}],"version-history":[{"count":2,"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/posts\/6855\/revisions"}],"predecessor-version":[{"id":6858,"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/posts\/6855\/revisions\/6858"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/media\/6856"}],"wp:attachment":[{"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/media?parent=6855"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/categories?post=6855"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sidwaya.info\/sport\/wp-json\/wp\/v2\/tags?post=6855"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}